{"id":8674,"date":"2019-06-06T13:25:22","date_gmt":"2019-06-06T16:25:22","guid":{"rendered":"https:\/\/www.adeba.com.ar\/?p=8674"},"modified":"2019-06-06T13:25:22","modified_gmt":"2019-06-06T16:25:22","slug":"resolucion-general-de-la-administracion-federal-de-ingresos-publicos-4501-2019","status":"publish","type":"post","link":"https:\/\/www.adeba.com.ar\/en\/resolucion-general-de-la-administracion-federal-de-ingresos-publicos-4501-2019\/","title":{"rendered":"Resoluci\u00f3n General de la Administraci\u00f3n Federal de Ingresos P\u00fablicos 4501\/2019"},"content":{"rendered":"<p><span style=\"color: #333333; font-family: 'Segoe UI','sans-serif'; font-size: 10pt;\">La Administraci\u00f3n Federal de Ingresos P\u00fablicos (AFIP) <strong><span style=\"font-family: 'Segoe UI','sans-serif';\">prorroga una semana de los vencimientos de la presentaci\u00f3n y pago de las declaraciones juradas de los impuestos a las ganancias<\/span><\/strong>, a la ganancia m\u00ednima presunta y sobre los bienes personales para las personas humanas.\u00a0 En consecuencia, las nuevas fechas de vencimiento para dichas presentaciones ser\u00e1n los d\u00edas 18, 19 y 21 de junio y las fechas de pago, ser\u00e1n los d\u00edas 19, 21 y 24 de junio.<br \/>\nAsimismo, la presente prorroga la <strong><span style=\"font-family: 'Segoe UI','sans-serif';\">presentaci\u00f3n de la declaraci\u00f3n jurada del impuesto cedular <\/span><\/strong>sobre la renta financiera hasta el 19\/7\/19 y habilita la posibilidad de presentar la declaraci\u00f3n jurada de manera simplificada.<\/span> <u><\/u><u><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impuestos a las Ganancias, sobre los Bienes Personales y Cedular. Per\u00edodo fiscal 2018. Plazo especial y modalidades para la presentaci\u00f3n de las declaraciones juradas. Norma complementaria. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/8674"}],"collection":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/comments?post=8674"}],"version-history":[{"count":1,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/8674\/revisions"}],"predecessor-version":[{"id":8675,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/8674\/revisions\/8675"}],"wp:attachment":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/media?parent=8674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/categories?post=8674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/tags?post=8674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}