{"id":19500,"date":"2021-04-21T17:03:44","date_gmt":"2021-04-21T20:03:44","guid":{"rendered":"https:\/\/www.adeba.com.ar\/?p=19500"},"modified":"2021-04-21T17:03:44","modified_gmt":"2021-04-21T20:03:44","slug":"las-tasas-municipales-un-exorbitante-costo-que-afecta-al-credito","status":"publish","type":"post","link":"https:\/\/www.adeba.com.ar\/en\/las-tasas-municipales-un-exorbitante-costo-que-afecta-al-credito\/","title":{"rendered":"Las tasas municipales: un exorbitante costo que afecta al cr\u00e9dito"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Introducci\u00f3n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las denominadas \u201ctasas municipales\u201d no son un impuesto. Son una contribuci\u00f3n econ\u00f3mica que pagan las personas y empresas en contraprestaci\u00f3n por un servicio prestado por los municipios, tales como el alumbrado, barrido y limpieza (ABL) o seguridad e higiene, entre otras cosas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, las tasas municipales que pagan entidades financieras son desproporcionadas y no guardan relaci\u00f3n con el costo de servicio efectivamente prestado. Muchos municipios cobran un monto excesivo bajo el concepto de tasas municipales y las utilizan como forma de recaudaci\u00f3n para financiar su gasto p\u00fablico. Es decir que se desnaturaliza el objeto de las tasas municipales y se transforman en un \u201cimpuesto\u201d sin contraprestaci\u00f3n. Cabe se\u00f1alar que, en principio, los municipios no tienen potestad de imponer impuestos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos n\u00fameros<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En algunos casos los montos de las tasas municipales son exorbitantes. Debido a que dicha informaci\u00f3n no es p\u00fablica, ADEBA ha realizado un relevamiento de las tasas municipales que los distintos distritos le han cobrado a los bancos asociados en los \u00faltimos a\u00f1os.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el relevamiento parcial de un grupo de bancos de ADEBA se registr\u00f3 que 3 municipios cobraron tasas municipales por m\u00e1s de $ 5.000.000 por cada sucursal bancaria en enero de 2021.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, se relevaron otros 42 municipios (mayormente en la provincia de Buenos Aires) que cobraron tasas municipales entre $ 1.000.000 y $ 5.000.000 mensual por cada sucursal. En 25 distritos cobraron entre $ 500.000 y $ 1.000.000 por cada sucursal. El peso de las tasas municipales son uno de los costos m\u00e1s significativos de la operatoria bancaria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para poner en perspectiva el peso de las tasas, basta con decir que, en los tres municipios m\u00e1s gravosos, la tasa municipal que paga una sucursal es superior a 50 salarios bancarios de nivel inicial. En los municipios \u201cintermedios\u201d el promedio es de 30 salarios b\u00e1sicos. Una sucursal t\u00edpica tiene entre 7 y 12 empleados. En otras palabras, los bancos les pagan mucho m\u00e1s a los municipios que a sus propios empleados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Menci\u00f3n aparte merece el cobro adicional que realizan algunos municipios a los bancos por cada ATM o terminal de autoservicio que poseen en las sucursales. Existen municipios en la provincia de Buenos Aires que cobran un extra del orden de $ 80.000 mensuales por cada cajero autom\u00e1tico que tenga la sucursal. Esta medida no solo encarece los servicios financieros y atenta contra la inclusi\u00f3n financiera, sino que tambi\u00e9n dificulta la expansi\u00f3n y mantenimiento de parque de cajeros autom\u00e1ticos. Cuantos m\u00e1s cajeros se instalen en una sucursal, m\u00e1s se deber\u00e1 pagar de tasas municipales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las tasas municipales no solo son desproporcionadas y elevadas, tambi\u00e9n tienen una tendencia creciente a lo largo de los a\u00f1os. Analizando tan solo los 20 municipios que cobran mayores tasas, se registraron alzas de hasta 300% en un a\u00f1o. Si bien las tasas municipales han tenido un comportamiento err\u00e1tico y heterog\u00e9neo en los \u00faltimos tres a\u00f1os, seg\u00fan cada jurisdicci\u00f3n, la tendencia es claramente alcista.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conclusi\u00f3n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Exorbitantes y crecientes tasas municipales encarecen los pr\u00e9stamos y dem\u00e1s servicios bancarios. Esto afecta negativamente la actividad financiera y el resto de las actividades de comercio y producci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las elevadas tasas municipales atentan directamente contra la bancarizaci\u00f3n e inclusi\u00f3n financiera. El costo de estas tasas eleva tan significativamente los costos de una sucursal bancaria, que desalienten la apertura de sucursales e instalaci\u00f3n de cajeros autom\u00e1ticos o terminales de autoservicio. Por ello, los m\u00e1s perjudicados por las altas tasas que los imponen municipios a las sucursales bancarias, son justamente los propios habitantes del municipio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sobre el tema Javier Bolzico, presidente de ADEBA, mencion\u00f3: <\/span><i><span style=\"font-weight: 400;\">\u201cEn aquellos municipios donde la presi\u00f3n fiscal sobre las sucursales y cajeros autom\u00e1ticos resulta desproporcionada, es esperable ver menor presencia de las entidades financieras. En contraposici\u00f3n, seguramente se vean m\u00e1s cajeros autom\u00e1ticos y sucursales en aquellos municipios cuyas tasas municipales guarden relaci\u00f3n con los servicios prestados\u201d.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Fijar las tasas municipales en niveles razonables, ser\u00eda un importante aporte de los municipios a la inclusi\u00f3n financiera y a disminuir el costo de los servicios bancarios, incrementando as\u00ed la actividad econ\u00f3mica local y el empleo privado en sus jurisdicciones.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3n Las denominadas \u201ctasas municipales\u201d no son un impuesto. Son una contribuci\u00f3n econ\u00f3mica que pagan las personas y empresas en contraprestaci\u00f3n por un servicio prestado por los municipios, tales como<span class=\"more\"><a class=\"more-link\" href=\"https:\/\/www.adeba.com.ar\/en\/las-tasas-municipales-un-exorbitante-costo-que-afecta-al-credito\/\">Seguir leyendo <span class=\"meta-nav\">&#8594;<\/span><\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":19501,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[247,4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/19500"}],"collection":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/comments?post=19500"}],"version-history":[{"count":2,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/19500\/revisions"}],"predecessor-version":[{"id":22659,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/19500\/revisions\/22659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/media\/19501"}],"wp:attachment":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/media?parent=19500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/categories?post=19500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/tags?post=19500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}