{"id":14996,"date":"2020-06-26T15:00:55","date_gmt":"2020-06-26T18:00:55","guid":{"rendered":"https:\/\/www.adeba.com.ar\/?p=14996"},"modified":"2020-06-26T15:00:55","modified_gmt":"2020-06-26T18:00:55","slug":"resolucion-del-instituto-nacional-de-asociativismo-y-economia-social-358-2020","status":"publish","type":"post","link":"https:\/\/www.adeba.com.ar\/en\/resolucion-del-instituto-nacional-de-asociativismo-y-economia-social-358-2020\/","title":{"rendered":"Resoluci\u00f3n del Instituto Nacional de Asociativismo y Econom\u00eda Social 358\/2020\u00a0&#8211;"},"content":{"rendered":"<p>Durante todo el per\u00edodo en que se restrinja la libre circulaci\u00f3n de las personas las entidades cooperativas y mutuales podr\u00e1n celebrar reuniones a distancia de los \u00f3rganos de gobierno, siempre que se cumplan con los recaudos m\u00ednimos establecidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Durante todo el per\u00edodo en que se restrinja la libre circulaci\u00f3n de las personas las entidades cooperativas y mutuales podr\u00e1n celebrar reuniones a distancia de los \u00f3rganos de gobierno, siempre que se cumplan con los recaudos m\u00ednimos establecidos.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/14996"}],"collection":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/comments?post=14996"}],"version-history":[{"count":1,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/14996\/revisions"}],"predecessor-version":[{"id":14997,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/posts\/14996\/revisions\/14997"}],"wp:attachment":[{"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/media?parent=14996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/categories?post=14996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adeba.com.ar\/en\/wp-json\/wp\/v2\/tags?post=14996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}